{"id":1892,"date":"2021-04-02T07:20:33","date_gmt":"2021-04-02T06:20:33","guid":{"rendered":"https:\/\/hooymanssubstrates.com\/metodo\/"},"modified":"2023-05-02T14:11:00","modified_gmt":"2023-05-02T13:11:00","slug":"metodo-de-trabajo","status":"publish","type":"page","link":"https:\/\/hooymanssubstrates.com\/es\/metodo-de-trabajo\/","title":{"rendered":"M\u00e9todo de trabajo"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong>PIONEROS<\/strong><\/h4>\n\n<p>Buscamos a diario soluciones innovadoras para perfeccionar nuestros procesos. Un sustrato de calidad define el \u00e9xito de nuestros cultivadores. Gracias a un proceso de producci\u00f3n altamente avanzado podemos garantizar la calidad del sustrato, pero existen m\u00e1s factores importantes para conseguir los mejores resultados en el cultivo. Gracias a una log\u00edstica, un servicio y un asesoramiento excelentes, nuestro sustrato puede viajar sin problemas por todo el mundo hasta llegar a los cultivadores.<\/p>\n\n\n\n\n<!-- tabfase -->\n<div id=\"tabfase-block_606b078bf698a\" class=\"tabfase alignfull\">\n    <ul class=\"tab_select\">\n                    <li data-tab=\".tab_1\">ACEPTAMOS LOS DESAF\u00cdOS <\/br>LOG\u00cdSTICOS<\/li>                    <li data-tab=\".tab_2\">ASESORAMIENTO PARA UNOS RESULTADOS \u00d3PTIMOS<\/li>                    <li data-tab=\".tab_3\">Preguntas espec\u00edficas de los clientes<\/li>                    <li data-tab=\".tab_4\">De la tierra a la mesa: los datos en tiempo real definen nuestras decisiones<\/li>            <\/ul>\n                    <div class=\"tab_content tab_1\">\n                                <div class=\"wrapper\">\n                    <section>\n                        <h6>ACEPTAMOS LOS DESAF\u00cdOS <\/br>LOG\u00cdSTICOS<\/h6>                        <p>El proceso de producci\u00f3n genera un sustrato de alta calidad, listo para su transporte y entrega al cultivador. En este caso, para garantizar la calidad hasta el momento de la entrega el proceso log\u00edstico es de suma importancia. El sustrato puede entregarse a granel y en paquetes, dentro y fuera de los Pa\u00edses Bajos. <\/p>\n<p>Las excelentes medidas de higiene durante el transporte, as\u00ed como los conocimientos y la experiencia de nuestros conductores, contribuyen a mantener la calidad del sustrato. La entrega y el llenado del sustrato en el lugar de cultivo es un proceso din\u00e1mico en el que el conductor asume el papel de asesor. Por eso, realizamos una estimaci\u00f3n previa de cada demanda y cada pedido con el fin de crear las condiciones id\u00f3neas durante el proceso de entrega del sustrato. <\/p>\n<p>Gracias a muchos a\u00f1os de experiencia log\u00edstica en el pa\u00eds y en el extranjero, conocemos todas las leyes y normativas regionales, nacionales y\/o internacionales. Estamos familiarizados con la expedici\u00f3n y solicitud de permisos, la preparaci\u00f3n de las hojas de ruta y exenciones adecuadas, as\u00ed como con las formalidades y reglamentos espec\u00edficos de cada pa\u00eds. <\/p>\n                    <\/section>\n                    <aside class=\"have_slider\">\n                                                                \n                                                                                                <div class=\"simple_slider\">\n                                        <ul>\n                                                                                        <li><img decoding=\"async\" srcset=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-3-nieuw-768x690.jpg 480w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-3-nieuw-960x862.jpg 768w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-3-nieuw-1200x1077.jpg 960w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-3-nieuw.jpg 1200w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-3-nieuw.jpg 2000w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-3-nieuw.jpg 3000w\" sizes=\"(max-width:479px) 480px, (min-width: 480px) and (max-width: 767px) 768px, (min-width: 768px) and (max-width: 959px) 960px, (min-width: 960px) and (max-width: 1200px) 1200px, 100vw\" src=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-3-nieuw-960x862.jpg\" alt=\"logistieke-uitdaging-3-nieuw\" \/><\/li>\n                                                                                        <li><img decoding=\"async\" srcset=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-1-nieuw-768x690.jpg 480w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-1-nieuw-960x862.jpg 768w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-1-nieuw-1200x1077.jpg 960w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-1-nieuw.jpg 1200w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-1-nieuw.jpg 2000w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-1-nieuw.jpg 3000w\" sizes=\"(max-width:479px) 480px, (min-width: 480px) and (max-width: 767px) 768px, (min-width: 768px) and (max-width: 959px) 960px, (min-width: 960px) and (max-width: 1200px) 1200px, 100vw\" src=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-1-nieuw-960x862.jpg\" alt=\"logistieke-uitdaging-1-nieuw\" \/><\/li>\n                                                                                        <li><img decoding=\"async\" srcset=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-2-nieuw-768x690.jpg 480w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-2-nieuw-960x862.jpg 768w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-2-nieuw-1200x1077.jpg 960w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-2-nieuw.jpg 1200w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-2-nieuw.jpg 2000w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-2-nieuw.jpg 3000w\" sizes=\"(max-width:479px) 480px, (min-width: 480px) and (max-width: 767px) 768px, (min-width: 768px) and (max-width: 959px) 960px, (min-width: 960px) and (max-width: 1200px) 1200px, 100vw\" src=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/logistieke-uitdaging-2-nieuw-960x862.jpg\" alt=\"logistieke-uitdaging-2-nieuw\" \/><\/li>\n                                                                                    <\/ul>\n                                    <\/div>\n                                            \n\n                                \n                                                \n                                                                <\/aside>\n                <\/div>\n            <\/div>\n                                <div class=\"tab_content tab_2 content_right media_bg\">\n                                <div class=\"wrapper\">\n                    <section>\n                        <h6>ASESORAMIENTO PARA UNOS RESULTADOS \u00d3PTIMOS<\/h6>                        <p>El conocimiento es nuestro ingrediente clave. Para cualquier cultivador, ya sea novel o experimentado, nuestros conocimientos pueden marcar la diferencia en la entrega y al inicio del cultivo. El asesoramiento durante el cultivo es uno de los pilares de nuestra organizaci\u00f3n. No solo constituye nuestro valor a\u00f1adido para los cultivadores, sino tambi\u00e9n un complemento de nuestro sustrato. <\/p>\n<p>Incluso el cultivador de champi\u00f1ones m\u00e1s experimentado se encuentra con sorpresas tarde o temprano. Ofrecemos asesoramiento en lo referente a decisiones y cuestiones sobre la t\u00e9cnica de cultivo. Cada entrega de sustrato debe cumplir plenamente con las expectativas de rendimiento y calidad. Nuestro equipo de especialistas con amplia experiencia est\u00e1 disponible todos los d\u00edas para responder a cualquier pregunta, adem\u00e1s de realizar visitas peri\u00f3dicas. El equipo coopera con nuestros clientes en la b\u00fasqueda de nuevas oportunidades para lograr un cultivo exitoso. \u00a1El mejor resultado para usted es tambi\u00e9n nuestro mejor resultado!<\/p>\n                    <\/section>\n                    <aside class=\"have_slider\">\n                                                                \n                                                                                                <div class=\"simple_slider\">\n                                        <ul>\n                                                                                        <li><img decoding=\"async\" srcset=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/beste-advies-img-768x334.png 480w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/beste-advies-img-960x418.png 768w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/beste-advies-img-1200x522.png 960w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/beste-advies-img.png 1200w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/beste-advies-img.png 2000w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/beste-advies-img.png 3000w\" sizes=\"(max-width:479px) 480px, (min-width: 480px) and (max-width: 767px) 768px, (min-width: 768px) and (max-width: 959px) 960px, (min-width: 960px) and (max-width: 1200px) 1200px, 100vw\" src=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/beste-advies-img-960x418.png\" alt=\"beste-advies-img\" \/><\/li>\n                                                                                        <li><img decoding=\"async\" srcset=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-3-768x334.jpg 480w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-3-960x418.jpg 768w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-3-1200x522.jpg 960w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-3.jpg 1200w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-3.jpg 2000w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-3.jpg 3000w\" sizes=\"(max-width:479px) 480px, (min-width: 480px) and (max-width: 767px) 768px, (min-width: 768px) and (max-width: 959px) 960px, (min-width: 960px) and (max-width: 1200px) 1200px, 100vw\" src=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-3-960x418.jpg\" alt=\"hooymans-beste-advies-3\" \/><\/li>\n                                                                                        <li><img decoding=\"async\" srcset=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-2-768x334.jpg 480w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-2-960x418.jpg 768w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-2-1200x522.jpg 960w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-2.jpg 1200w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-2.jpg 2000w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-2.jpg 3000w\" sizes=\"(max-width:479px) 480px, (min-width: 480px) and (max-width: 767px) 768px, (min-width: 768px) and (max-width: 959px) 960px, (min-width: 960px) and (max-width: 1200px) 1200px, 100vw\" src=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/hooymans-beste-advies-2-960x418.jpg\" alt=\"hooymans-beste-advies-2\" \/><\/li>\n                                                                                    <\/ul>\n                                    <\/div>\n                                            \n\n                                \n                                                \n                                                                <\/aside>\n                <\/div>\n            <\/div>\n                                <div class=\"tab_content tab_3\">\n                                <div class=\"wrapper\">\n                    <section>\n                        <h6>Preguntas espec\u00edficas de los clientes<\/h6>                        <p>El sustrato es un producto natural y, por tanto, nunca es exactamente igual. Nuestro sustrato es tan \u00fanico como nuestros clientes. El sustrato de la fase 2 puede inocularse y cultivarse con distintas cepas de cultivo a petici\u00f3n del cultivador. Aqu\u00ed son esenciales una buena coordinaci\u00f3n con el cultivador y el intercambio de informaci\u00f3n para adecuar el sustrato a los distintos tipos de sistemas de cultivo y\/o m\u00e9todos de recolecci\u00f3n. En el caso de clientes grandes incluso se fabrica un sustrato de producci\u00f3n independiente. <\/p>\n                    <\/section>\n                    <aside >\n                                                                \n                                                            <figure class=\"simple_image\">\n                                    <img decoding=\"async\" srcset=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/grondstoffen-hooymans-substrates-768x690.jpg 480w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/grondstoffen-hooymans-substrates-960x862.jpg 768w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/grondstoffen-hooymans-substrates-1200x1077.jpg 960w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/grondstoffen-hooymans-substrates.jpg 1200w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/grondstoffen-hooymans-substrates.jpg 2000w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/grondstoffen-hooymans-substrates.jpg 3000w\" sizes=\"(max-width:479px) 480px, (min-width: 480px) and (max-width: 767px) 768px, (min-width: 768px) and (max-width: 959px) 960px, (min-width: 960px) and (max-width: 1200px) 1200px, 100vw\" src=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/09\/grondstoffen-hooymans-substrates-960x862.jpg\" alt=\"grondstoffen-hooymans-substrates\" \/>                                <\/figure>\n\n\n                                                \n                                                                <\/aside>\n                <\/div>\n            <\/div>\n                                <div class=\"tab_content tab_4 content_right\">\n                <div class=\"bg_color\" style=\"background-color:#f2f0eb\"><\/div>                <div class=\"wrapper\">\n                    <section>\n                        <h6>De la tierra a la mesa: los datos en tiempo real definen nuestras decisiones<\/h6>                        <p>La garant\u00eda de calidad exige comprender la cadena de producci\u00f3n. Por ello, la trazabilidad est\u00e1 cada vez m\u00e1s integrada en nuestra organizaci\u00f3n. Las materias primas que suministramos pueden rastrearse por lotes hasta su origen y su entrega. Este sistema infalible de seguimiento y localizaci\u00f3n permite conocer el historial de cada entrega, tanto dentro de los Pa\u00edses Bajos como a escala internacional. <\/p>\n<p>La trazabilidad de las materias primas es un componente clave en la gesti\u00f3n de la producci\u00f3n. En colaboraci\u00f3n con otros laboratorios externos acreditados, nuestro laboratorio analiza con precisi\u00f3n todas las materias primas que se ofrecen. A cada entrega se le asigna un n\u00famero de lote propio y se registra y documenta la temperatura durante el transporte. De este modo, se controla y monitorea al m\u00e1ximo la calidad del sustrato. <\/p>\n                    <\/section>\n                    <aside >\n                                                                \n                                                            <figure class=\"simple_image\">\n                                    <img decoding=\"async\" srcset=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/Van-grond-tot-mond-1.jpg 480w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/Van-grond-tot-mond-1.jpg 768w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/Van-grond-tot-mond-1.jpg 960w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/Van-grond-tot-mond-1.jpg 1200w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/Van-grond-tot-mond-1.jpg 2000w, https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/Van-grond-tot-mond-1.jpg 3000w\" sizes=\"(max-width:479px) 480px, (min-width: 480px) and (max-width: 767px) 768px, (min-width: 768px) and (max-width: 959px) 960px, (min-width: 960px) and (max-width: 1200px) 1200px, 100vw\" src=\"https:\/\/hooymanssubstrates.com\/wp-content\/uploads\/2021\/04\/Van-grond-tot-mond-1.jpg\" alt=\"Van-grond-tot-mond-1\" \/>                                <\/figure>\n\n\n                                                \n                                                                <\/aside>\n                <\/div>\n            <\/div>\n                    <\/div>\n<!-- \/tabfase -->\n<script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gform_legacy_markup_wrapper gform-theme--no-framework substraten_form_wrapper' data-form-theme='legacy' data-form-index='0' id='gform_wrapper_3' ><div id='gf_3' class='gform_anchor' tabindex='-1'><\/div>\n                        <div class='gform_heading'>\n                            <p class='gform_description'><\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_3' id='gform_3' class='substraten_form' action='\/es\/wp-json\/wp\/v2\/pages\/1892#gf_3' data-formid='3' novalidate>\n                        <div class='gform-body gform_body'><ul id='gform_fields_3' class='gform_fields top_label form_sublabel_below description_below validation_below'><li id=\"field_3_10\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_10'>Instagram<\/label><div class='ginput_container'><input name='input_10' id='input_3_10' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_3_10'>Este campo es un campo de validaci\u00f3n y debe quedar sin cambios.<\/div><\/li><li id=\"field_3_6\" class=\"gfield gfield--type-html gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h4>Quiere saber <strong>m\u00e1s<\/strong> sobre los sustratos de Hooymans?<\/h4>\n<p>Rellena el siguiente formulario de contacto y te informaremos lo antes posible.<\/p><\/li><li id=\"field_3_1\" class=\"gfield gfield--type-text gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_1'>Nombre:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_3_1' type='text' value='' class='medium'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_3_2\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_2'>Correo electr\u00f3nico:<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_3_2' type='email' value='' class='medium'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/li><li id=\"field_3_3\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_3'>Empresa \/ organizaci\u00f3n:<\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_3_3' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_3_5\" class=\"gfield gfield--type-text field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_5'>Pa\u00eds:<\/label><div class='ginput_container ginput_container_text'><input name='input_5' id='input_3_5' type='text' value='' class='medium'      aria-invalid=\"false\"   \/><\/div><\/li><li id=\"field_3_4\" class=\"gfield gfield--type-textarea field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_4'>Mensaje:<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_3_4' class='textarea medium'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/li><li id=\"field_3_9\" class=\"gfield gfield--type-captcha field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_3_9'>CAPTCHA<\/label><div id='input_3_9' class='ginput_container ginput_recaptcha' data-sitekey='6LePx98lAAAAAKOLe0OSr2WNtwOTP24Xfc5BBZTc'  data-theme='light' data-tabindex='-1' data-size='invisible' data-badge='bottomright'><\/div><\/li><\/ul><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_3' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Enviar:'  \/> <input type='hidden' name='gform_ajax' value='form_id=3&amp;title=&amp;description=1&amp;tabindex=0&amp;theme=legacy&amp;styles=[]&amp;hash=1771566329064c3aebc3f2350c03d1d5' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_3' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_3' id='gform_theme_3' value='legacy' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_3' id='gform_style_settings_3' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_3' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='3' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='\/R+xMGWsSwFjiUo9ztBdnm8Vttc+6xvZJR1cvZoOmBmMw7viW2\/NEIrtcqgMmt1H4lZvTkh\/aUmbuJClhpinq3LI6lHMhHpRykyhyvcOlPcHBrw=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_3' value='WyJbXSIsIjA5OWE5NWZiYWZjOGE0MjIxNTA4NDdjNGIyNjJmYjM3Il0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_3' id='gform_target_page_number_3' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_3' id='gform_source_page_number_3' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_3' id='gform_ajax_frame_3' title='Este iframe contiene la l\u00f3gica necesaria para gestionar formularios con ajax activado.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 3, 'https:\/\/hooymanssubstrates.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_3').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_3');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_3').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_3').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_3').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_3').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_3').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_3').val();gformInitSpinner( 3, 'https:\/\/hooymanssubstrates.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [3, current_page]);window['gf_submitting_3'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_3').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_3').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [3]);window['gf_submitting_3'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_3').text());}else{jQuery('#gform_3').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"3\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_3\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_3\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_3\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 3, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>PIONEROS Buscamos a diario soluciones innovadoras para perfeccionar nuestros procesos. Un sustrato de calidad define el \u00e9xito de nuestros cultivadores. Gracias a un proceso de producci\u00f3n altamente avanzado podemos garantizar la calidad del sustrato, pero existen m\u00e1s factores importantes para conseguir los mejores resultados en el cultivo. Gracias a una log\u00edstica, un servicio y un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":771,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-1892","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/hooymanssubstrates.com\/es\/wp-json\/wp\/v2\/pages\/1892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hooymanssubstrates.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hooymanssubstrates.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hooymanssubstrates.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hooymanssubstrates.com\/es\/wp-json\/wp\/v2\/comments?post=1892"}],"version-history":[{"count":2,"href":"https:\/\/hooymanssubstrates.com\/es\/wp-json\/wp\/v2\/pages\/1892\/revisions"}],"predecessor-version":[{"id":1911,"href":"https:\/\/hooymanssubstrates.com\/es\/wp-json\/wp\/v2\/pages\/1892\/revisions\/1911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hooymanssubstrates.com\/es\/wp-json\/wp\/v2\/media\/771"}],"wp:attachment":[{"href":"https:\/\/hooymanssubstrates.com\/es\/wp-json\/wp\/v2\/media?parent=1892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}